{"id":78124,"date":"2022-08-19T16:08:54","date_gmt":"2022-08-19T09:08:54","guid":{"rendered":"https:\/\/construction-property.com\/%e1%9e%94%e1%9e%85%e1%9f%92%e1%9e%85%e1%9e%bb%e1%9e%94%e1%9f%92%e1%9e%94%e1%9e%93%e1%9f%92%e1%9e%93-%e1%9e%80%e1%9f%92%e1%9e%93%e1%9e%bb%e1%9e%84%e1%9e%a7%e1%9e%91%e1%9f%92%e1%9e%99%e1%9e%b6%e1%9e%93\/"},"modified":"2022-08-19T16:08:54","modified_gmt":"2022-08-19T09:08:54","slug":"%e1%9e%94%e1%9e%85%e1%9f%92%e1%9e%85%e1%9e%bb%e1%9e%94%e1%9f%92%e1%9e%94%e1%9e%93%e1%9f%92%e1%9e%93-%e1%9e%80%e1%9f%92%e1%9e%93%e1%9e%bb%e1%9e%84%e1%9e%a7%e1%9e%91%e1%9f%92%e1%9e%99%e1%9e%b6%e1%9e%93","status":"publish","type":"post","link":"https:\/\/construction-property.com\/km\/%e1%9e%94%e1%9e%85%e1%9f%92%e1%9e%85%e1%9e%bb%e1%9e%94%e1%9f%92%e1%9e%94%e1%9e%93%e1%9f%92%e1%9e%93-%e1%9e%80%e1%9f%92%e1%9e%93%e1%9e%bb%e1%9e%84%e1%9e%a7%e1%9e%91%e1%9f%92%e1%9e%99%e1%9e%b6%e1%9e%93\/","title":{"rendered":"\u1794\u1785\u17d2\u1785\u17bb\u1794\u17d2\u1794\u1793\u17d2\u1793 \u1780\u17d2\u1793\u17bb\u1784\u17a7\u1791\u17d2\u1799\u17b6\u1793\u1787\u17b6\u178f\u17b7\u17a2\u1784\u17d2\u1782\u179a\u1798\u17b6\u1793\u179f\u17c6\u178e\u1784\u17cb\u1781\u17bb\u179f\u1785\u17d2\u1794\u17b6\u1794\u17cb\u1787\u17b6\u1784 \u17e8\u1796\u17b6\u1793\u17cb\u1780\u179a\u178e\u17b8"},"content":{"rendered":"<p>\u1780\u17d2\u179a\u17c4\u1799\u1798\u17b6\u1793\u1780\u17b6\u179a\u1785\u17bb\u17c7\u178f\u17d2\u179a\u17bd\u178f\u1796\u17b7\u1793\u17b7\u178f\u17d2\u1799\u178a\u17c4\u1799\u1795\u17d2\u1791\u17b6\u179b\u17cb\u179a\u1794\u179f\u17cb \u17af\u1780\u17a7\u178f\u17d2\u178f\u1798\u1787\u17b6 \u179f\u17bb\u1795\u17b6\u179a\u17c9\u17b6 \u179a\u178a\u17d2\u178b\u1798\u1793\u17d2\u178f\u17d2\u179a\u17b8\u1780\u17d2\u179a\u179f\u17bd\u1784\u179a\u17c0\u1794\u1785\u17c6\u178a\u17c2\u1793\u178a\u17b8\u1793\u1782\u179a\u17bc\u1794\u1793\u17b8\u1799\u1780\u1798\u17d2\u1798 \u1793\u17b7\u1784\u179f\u17c6\u178e\u1784\u17cb \u1794\u17b6\u1793\u179a\u1780\u1783\u17be\u1789\u1790\u17b6\u179a\u17a0\u17bc\u178f\u178a\u179b\u17cb\u1794\u1785\u17d2\u1785\u17bb\u1794\u17d2\u1794\u1793\u17d2\u1793 \u1798\u17b6\u1793\u179f\u17c6\u178e\u1784\u17cb\u1781\u17bb\u179f\u1785\u17d2\u1794\u17b6\u1794\u17cb\u179a\u17a0\u17bc\u178f\u178a\u179b\u17cb\u1787\u17b6\u1784 \u17e8\u17e0\u17e0\u17e0\u1780\u179a\u178e\u17b8 \u179f\u17d2\u1790\u17b7\u178f\u1780\u17d2\u1793\u17bb\u1784\u17a7\u1791\u17d2\u1799\u17b6\u1793\u1787\u17b6\u178f\u17b7\u17a2\u1784\u17d2\u1782\u179a \u1781\u178e\u17c8\u1798\u17b6\u1793\u178f\u17c2 \u17e2\u17e0\u17e0\u1780\u179a\u178e\u17b8\u1794\u17c9\u17bb\u178e\u17d2\u178e\u17c4\u17c7\u178a\u17c2\u179b\u1794\u17b6\u1793\u179a\u17be\u1785\u17c1\u1789\u200b\u17d4 \u1793\u17c1\u17c7\u1794\u17be\u1799\u17c4\u1784\u178f\u17b6\u1798\u1780\u17b6\u179a\u179b\u17be\u1780\u17a1\u17be\u1784\u179a\u1794\u179f\u17cb\u17af\u1780\u17a7\u178f\u17d2\u178f\u1798\u1787\u17b6 \u179f\u17bb\u1795\u17b6\u179a\u17c9\u17b6 \u1787\u17b6\u1798\u17bd\u1799\u17a7\u1780\u1789\u17c9\u17b6\u1789\u17c9\u17bc\u1793\u17c5\u1790\u17d2\u1784\u17c3\u1791\u17b8\u17e1\u17e7 \u179f\u17b8\u17a0\u17b6 \u17e2\u17e0\u17e2\u17e2\u17d4<\/p>\n<p>\u1780\u17d2\u179a\u179f\u17bd\u1784\u179a\u17c0\u1794\u1785\u17c6\u178a\u17c2\u1793\u178a\u17b8\u1793\u1782\u179a\u17bc\u1794\u1793\u17b8\u1799\u1780\u1798\u17d2\u1798 \u1793\u17b7\u1784\u179f\u17c6\u178e\u1784\u17cb \u1794\u17b6\u1793\u179a\u17c0\u1794\u1785\u17c6\u1799\u17bb\u1791\u17d2\u1792\u1793\u17b6\u1780\u17b6\u179a\u1791\u17d2\u179a\u1784\u17cb\u1791\u17d2\u179a\u17b6\u1799\u1792\u17c6 \u178a\u17be\u1798\u17d2\u1794\u17b8\u1785\u17bb\u17c7\u179c\u17b6\u179f\u17cb\u179c\u17c2\u1784 \u1780\u17c6\u178e\u178f\u17cb\u1793\u17b7\u1799\u17b6\u1798\u1780\u17b6\u1780\u17d2\u1794\u17b6\u179b\u178a\u17b8 \u1793\u17b7\u1784\u17a2\u178f\u17d2\u178f\u179f\u1789\u17d2\u1789\u17b6\u178e\u17a2\u17d2\u1793\u1780\u1780\u17b6\u1793\u17cb\u1780\u17b6\u1794\u17cb\u178a\u17b8 \u1793\u17b7\u1784\u179f\u17c6\u178e\u1784\u17cb\u1781\u17bb\u179f\u1785\u17d2\u1794\u17b6\u1794\u17cb\u1780\u17d2\u1793\u17bb\u1784\u178f\u17c6\u1794\u1793\u17cb\u179a\u1798\u178e\u17b8\u178a\u17d2\u178b\u17b6\u1793\u17a2\u1784\u17d2\u1782\u179a \u1793\u17b7\u1784\u178f\u17c6\u1794\u1793\u17cb\u178a\u17c2\u179b\u179f\u17d2\u1790\u17b7\u178f\u1780\u17d2\u179a\u17c4\u1798\u1780\u17b6\u179a\u1782\u17d2\u179a\u1794\u17cb\u1782\u17d2\u179a\u1784\u179a\u1794\u179f\u17cb\u17a2\u17b6\u1787\u17d2\u1789\u17b6\u1792\u179a\u1787\u17b6\u178f\u17b7\u17a2\u1794\u17d2\u179f\u179a\u17b6 \u1780\u17b6\u179b\u1796\u17b8\u1790\u17d2\u1784\u17c3\u1791\u17b8\u17e1\u17e7 \u179f\u17b8\u17a0\u17b6 \u17e2\u17e0\u17e2\u17e2\u17d4 (\u17a2\u17b6\u1793<a href=\"https:\/\/construction-property.com\/%e1%9e%9a%e1%9e%8a%e1%9f%92%e1%9e%8b%e1%9e%94%e1%9e%be%e1%9e%80%e1%9e%99%e1%9e%bb%e1%9e%91%e1%9f%92%e1%9e%92%e1%9e%93%e1%9e%b6%e1%9e%80%e1%9e%b6%e1%9e%9a%e1%9e%96%e1%9e%b7%e1%9e%9f%e1%9f%81%e1%9e%9f\/?lang=km\">\u1794\u1793\u17d2\u1790\u17c2\u1798<\/a>)<\/p>\n<p>\u1790\u17d2\u179b\u17c2\u1784\u1780\u17d2\u1793\u17bb\u1784\u1796\u17c1\u179b\u1785\u17bb\u17c7\u178f\u17d2\u179a\u17bd\u178f\u1796\u17b7\u1793\u17b7\u178f\u17d2\u1799\u1793\u17c1\u17c7\u178a\u17c2\u179a \u17af\u1780\u17a7\u178f\u17d2\u178f\u1798\u1787\u17b6 \u179f\u17bb\u1795\u17b6\u179a\u17c9\u17b6 \u1794\u17b6\u1793\u1794\u1784\u17d2\u17a0\u17b6\u1789\u1790\u17b6\u1780\u17d2\u1793\u17bb\u1784\u179a\u1799\u17c8\u1796\u17c1\u179b \u17e3\u1781\u17c2\u1785\u17bb\u1784\u1780\u17d2\u179a\u17c4\u1799\u1793\u17c1\u17c7 \u1798\u17b6\u1793\u179f\u17c6\u178e\u1784\u17cb\u1781\u17bb\u179f\u1785\u17d2\u1794\u17b6\u1794\u17cb\u1790\u17d2\u1798\u17b8\u1780\u17be\u178f\u179a\u17a0\u17bc\u178f\u178a\u179b\u17cb \u17e3\u17e9\u17e8\u1780\u179a\u178e\u17b8 \u178a\u17c2\u179b\u1780\u17d2\u1793\u17bb\u1784\u1793\u17c4\u17c7\u1794\u17b6\u1793\u179a\u17bb\u17c7\u179a\u17be\u1785\u17c1\u1789\u1794\u17b6\u1793\u178f\u17d2\u179a\u17b9\u1798\u178f\u17c2\u1787\u17b6\u1784 \u17e2\u17e0\u17e0\u1780\u179a\u178e\u17b8 \u1794\u17c9\u17bb\u178e\u17d2\u178e\u17c4\u17c7\u17d4<\/p>\n<p>\u178a\u17c4\u1799\u17a1\u17c2\u1780 \u1782\u17b7\u178f\u1798\u1780\u1791\u179b\u17cb\u1794\u1785\u17d2\u1785\u17bb\u1794\u17d2\u1794\u1793\u17d2\u1793\u179f\u17c6\u178e\u1784\u17cb\u1781\u17bb\u179f\u1785\u17d2\u1794\u17b6\u1794\u17cb\u1787\u17b6\u179f\u179a\u17bb\u1794\u1798\u17b6\u1793\u178a\u179b\u17cb\u1791\u17c5 \u17e8\u1796\u17b6\u1793\u17cb\u1780\u179a\u178e\u17b8\u17af\u178e\u17c4\u17c7\u17d4<\/p>\n<p>\u17af\u1780\u17a7\u178f\u17d2\u178f\u1798\u1794\u17b6\u1793\u179a\u1798\u17d2\u179b\u17b9\u1780\u178a\u17c2\u179a\u1790\u17b6 \u1785\u17c6\u1796\u17c4\u17c7\u17a2\u17d2\u1793\u1780\u1785\u17c1\u1789\u178f\u179c\u17c9\u17b6\u1780\u17b6\u179a\u1796\u17b6\u179a\u179f\u17c6\u178e\u1784\u17cb\u1781\u17bb\u179f\u1785\u17d2\u1794\u17b6\u1794\u17cb\u1791\u17b6\u17c6\u1784\u1793\u17c1\u17c7 \u179a\u178a\u17d2\u178b\u1793\u17b9\u1784\u1785\u17b6\u178f\u17cb\u179c\u17b7\u1792\u17b6\u1793\u1780\u17b6\u179a\u1785\u17d2\u1794\u17b6\u1794\u17cb \u17d4<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u1780\u17d2\u179a\u17c4\u1799\u1798\u17b6\u1793\u1780\u17b6\u179a\u1785\u17bb\u17c7\u178f\u17d2\u179a\u17bd\u178f\u1796\u17b7\u1793\u17b7\u178f\u17d2\u1799\u178a\u17c4\u1799\u1795\u17d2\u1791\u17b6\u179b\u17cb\u179a\u1794\u179f\u17cb \u17af\u1780\u17a7\u178f\u17d2\u178f\u1798\u1787\u17b6 \u179f\u17bb\u1795\u17b6\u179a [&hellip;]<\/p>\n","protected":false},"author":84,"featured_media":78125,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"nf_dc_page":"","footnotes":""},"categories":[1496,1497,1],"tags":[828,2209],"class_list":["post-78124","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-1496","category-1497","category-uncategorized","tag-828","tag---km-828"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u1794\u1785\u17d2\u1785\u17bb\u1794\u17d2\u1794\u1793\u17d2\u1793 \u1780\u17d2\u1793\u17bb\u1784\u17a7\u1791\u17d2\u1799\u17b6\u1793\u1787\u17b6\u178f\u17b7\u17a2\u1784\u17d2\u1782\u179a\u1798\u17b6\u1793\u179f\u17c6\u178e\u1784\u17cb\u1781\u17bb\u179f\u1785\u17d2\u1794\u17b6\u1794\u17cb\u1787\u17b6\u1784 \u17e8\u1796\u17b6\u1793\u17cb\u1780\u179a\u178e\u17b8 - Construction &amp; Property News<\/title>\n<meta name=\"description\" content=\"\u1780\u17d2\u179a\u17c4\u1799\u1798\u17b6\u1793\u1780\u17b6\u179a\u1785\u17bb\u17c7\u178f\u17d2\u179a\u17bd\u178f\u1796\u17b7\u1793\u17b7\u178f\u17d2\u1799\u178a\u17c4\u1799\u1795\u17d2\u1791\u17b6\u179b\u17cb\u179a\u1794\u179f\u17cb \u17af\u1780\u17a7\u178f\u17d2\u178f\u1798\u1787\u17b6 \u179f\u17bb\u1795\u17b6\u179a\u17c9\u17b6 \u179a\u178a\u17d2\u178b\u1798\u1793\u17d2\u178f\u17d2\u179a\u17b8\u1780\u17d2\u179a\u179f\u17bd\u1784\u179a\u17c0\u1794\u1785\u17c6\u178a\u17c2\u1793\u178a\u17b8\u1793\u1782\u179a\u17bc\u1794\u1793\u17b8\u1799\u1780\u1798\u17d2\u1798 \u1793\u17b7\u1784\u179f\u17c6\u178e\u1784\u17cb \u1794\u17b6\u1793\u179a\u1780\u1783\u17be\u1789\u1790\u17b6\u179a\u17a0\u17bc\u178f\u178a\u179b\u17cb\u1794\u1785\u17d2\u1785\u17bb\u1794\u17d2\u1794\u1793\u17d2\u1793\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/construction-property.com\/km\/%e1%9e%94%e1%9e%85%e1%9f%92%e1%9e%85%e1%9e%bb%e1%9e%94%e1%9f%92%e1%9e%94%e1%9e%93%e1%9f%92%e1%9e%93-%e1%9e%80%e1%9f%92%e1%9e%93%e1%9e%bb%e1%9e%84%e1%9e%a7%e1%9e%91%e1%9f%92%e1%9e%99%e1%9e%b6%e1%9e%93\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u1794\u1785\u17d2\u1785\u17bb\u1794\u17d2\u1794\u1793\u17d2\u1793 \u1780\u17d2\u1793\u17bb\u1784\u17a7\u1791\u17d2\u1799\u17b6\u1793\u1787\u17b6\u178f\u17b7\u17a2\u1784\u17d2\u1782\u179a\u1798\u17b6\u1793\u179f\u17c6\u178e\u1784\u17cb\u1781\u17bb\u179f\u1785\u17d2\u1794\u17b6\u1794\u17cb\u1787\u17b6\u1784 \u17e8\u1796\u17b6\u1793\u17cb\u1780\u179a\u178e\u17b8 - Construction &amp; Property News\" \/>\n<meta property=\"og:description\" content=\"\u1780\u17d2\u179a\u17c4\u1799\u1798\u17b6\u1793\u1780\u17b6\u179a\u1785\u17bb\u17c7\u178f\u17d2\u179a\u17bd\u178f\u1796\u17b7\u1793\u17b7\u178f\u17d2\u1799\u178a\u17c4\u1799\u1795\u17d2\u1791\u17b6\u179b\u17cb\u179a\u1794\u179f\u17cb \u17af\u1780\u17a7\u178f\u17d2\u178f\u1798\u1787\u17b6 \u179f\u17bb\u1795\u17b6\u179a\u17c9\u17b6 \u179a\u178a\u17d2\u178b\u1798\u1793\u17d2\u178f\u17d2\u179a\u17b8\u1780\u17d2\u179a\u179f\u17bd\u1784\u179a\u17c0\u1794\u1785\u17c6\u178a\u17c2\u1793\u178a\u17b8\u1793\u1782\u179a\u17bc\u1794\u1793\u17b8\u1799\u1780\u1798\u17d2\u1798 \u1793\u17b7\u1784\u179f\u17c6\u178e\u1784\u17cb \u1794\u17b6\u1793\u179a\u1780\u1783\u17be\u1789\u1790\u17b6\u179a\u17a0\u17bc\u178f\u178a\u179b\u17cb\u1794\u1785\u17d2\u1785\u17bb\u1794\u17d2\u1794\u1793\u17d2\u1793\" \/>\n<meta property=\"og:url\" content=\"https:\/\/construction-property.com\/km\/%e1%9e%94%e1%9e%85%e1%9f%92%e1%9e%85%e1%9e%bb%e1%9e%94%e1%9f%92%e1%9e%94%e1%9e%93%e1%9f%92%e1%9e%93-%e1%9e%80%e1%9f%92%e1%9e%93%e1%9e%bb%e1%9e%84%e1%9e%a7%e1%9e%91%e1%9f%92%e1%9e%99%e1%9e%b6%e1%9e%93\/\" \/>\n<meta property=\"og:site_name\" content=\"Construction &amp; Property News\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/construction-property.com\/km\/china-agrees-to-lend-money-to-build-a-new-bridge-connecting-chak-angre-krom-and-prek-pra\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-19T09:08:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/construction-property.com\/wp-content\/uploads\/2022\/08\/CPM_8_illegal-Construction_19-08-2022.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Sommana Yan\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sommana Yan\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/construction-property.com\\\/km\\\/%e1%9e%94%e1%9e%85%e1%9f%92%e1%9e%85%e1%9e%bb%e1%9e%94%e1%9f%92%e1%9e%94%e1%9e%93%e1%9f%92%e1%9e%93-%e1%9e%80%e1%9f%92%e1%9e%93%e1%9e%bb%e1%9e%84%e1%9e%a7%e1%9e%91%e1%9f%92%e1%9e%99%e1%9e%b6%e1%9e%93\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/construction-property.com\\\/km\\\/%e1%9e%94%e1%9e%85%e1%9f%92%e1%9e%85%e1%9e%bb%e1%9e%94%e1%9f%92%e1%9e%94%e1%9e%93%e1%9f%92%e1%9e%93-%e1%9e%80%e1%9f%92%e1%9e%93%e1%9e%bb%e1%9e%84%e1%9e%a7%e1%9e%91%e1%9f%92%e1%9e%99%e1%9e%b6%e1%9e%93\\\/\"},\"author\":{\"name\":\"Sommana Yan\",\"@id\":\"https:\\\/\\\/construction-property.com\\\/km\\\/#\\\/schema\\\/person\\\/2e38ef685b96188d052f0f9dcc8f8772\"},\"headline\":\"\u1794\u1785\u17d2\u1785\u17bb\u1794\u17d2\u1794\u1793\u17d2\u1793 \u1780\u17d2\u1793\u17bb\u1784\u17a7\u1791\u17d2\u1799\u17b6\u1793\u1787\u17b6\u178f\u17b7\u17a2\u1784\u17d2\u1782\u179a\u1798\u17b6\u1793\u179f\u17c6\u178e\u1784\u17cb\u1781\u17bb\u179f\u1785\u17d2\u1794\u17b6\u1794\u17cb\u1787\u17b6\u1784 \u17e8\u1796\u17b6\u1793\u17cb\u1780\u179a\u178e\u17b8\",\"datePublished\":\"2022-08-19T09:08:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/construction-property.com\\\/km\\\/%e1%9e%94%e1%9e%85%e1%9f%92%e1%9e%85%e1%9e%bb%e1%9e%94%e1%9f%92%e1%9e%94%e1%9e%93%e1%9f%92%e1%9e%93-%e1%9e%80%e1%9f%92%e1%9e%93%e1%9e%bb%e1%9e%84%e1%9e%a7%e1%9e%91%e1%9f%92%e1%9e%99%e1%9e%b6%e1%9e%93\\\/\"},\"wordCount\":0,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/construction-property.com\\\/km\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/construction-property.com\\\/km\\\/%e1%9e%94%e1%9e%85%e1%9f%92%e1%9e%85%e1%9e%bb%e1%9e%94%e1%9f%92%e1%9e%94%e1%9e%93%e1%9f%92%e1%9e%93-%e1%9e%80%e1%9f%92%e1%9e%93%e1%9e%bb%e1%9e%84%e1%9e%a7%e1%9e%91%e1%9f%92%e1%9e%99%e1%9e%b6%e1%9e%93\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/construction-property.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/CPM_8_illegal-Construction_19-08-2022.png\",\"keywords\":[\"\u1785\u17d2\u1794\u17b6\u1794\u17cb \u1793\u17b7\u1784\u1794\u1789\u17d2\u1789\u17b6\u178f\u17d2\u178f\u17b7\",\"\u1785\u17d2\u1794\u17b6\u1794\u17cb \u1793\u17b7\u1784\u1794\u1789\u17d2\u1789\u17b6\u178f\u17d2\u178f\u17b7\"],\"articleSection\":[\"\u1796\u17d0\u178f\u17cc\u1798\u17b6\u1793\u17a2\u1785\u179b\u1793\u1791\u17d2\u179a\u1796\u17d2\u1799\",\"\u1796\u17d0\u178f\u17cc\u1798\u17b6\u1793\u1780\u17d2\u1793\u17bb\u1784\u179f\u17d2\u179a\u17bb\u1780\",\"Uncategorized\"],\"inLanguage\":\"km\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/construction-property.com\\\/km\\\/%e1%9e%94%e1%9e%85%e1%9f%92%e1%9e%85%e1%9e%bb%e1%9e%94%e1%9f%92%e1%9e%94%e1%9e%93%e1%9f%92%e1%9e%93-%e1%9e%80%e1%9f%92%e1%9e%93%e1%9e%bb%e1%9e%84%e1%9e%a7%e1%9e%91%e1%9f%92%e1%9e%99%e1%9e%b6%e1%9e%93\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/construction-property.com\\\/km\\\/%e1%9e%94%e1%9e%85%e1%9f%92%e1%9e%85%e1%9e%bb%e1%9e%94%e1%9f%92%e1%9e%94%e1%9e%93%e1%9f%92%e1%9e%93-%e1%9e%80%e1%9f%92%e1%9e%93%e1%9e%bb%e1%9e%84%e1%9e%a7%e1%9e%91%e1%9f%92%e1%9e%99%e1%9e%b6%e1%9e%93\\\/\",\"url\":\"https:\\\/\\\/construction-property.com\\\/km\\\/%e1%9e%94%e1%9e%85%e1%9f%92%e1%9e%85%e1%9e%bb%e1%9e%94%e1%9f%92%e1%9e%94%e1%9e%93%e1%9f%92%e1%9e%93-%e1%9e%80%e1%9f%92%e1%9e%93%e1%9e%bb%e1%9e%84%e1%9e%a7%e1%9e%91%e1%9f%92%e1%9e%99%e1%9e%b6%e1%9e%93\\\/\",\"name\":\"\u1794\u1785\u17d2\u1785\u17bb\u1794\u17d2\u1794\u1793\u17d2\u1793 \u1780\u17d2\u1793\u17bb\u1784\u17a7\u1791\u17d2\u1799\u17b6\u1793\u1787\u17b6\u178f\u17b7\u17a2\u1784\u17d2\u1782\u179a\u1798\u17b6\u1793\u179f\u17c6\u178e\u1784\u17cb\u1781\u17bb\u179f\u1785\u17d2\u1794\u17b6\u1794\u17cb\u1787\u17b6\u1784 \u17e8\u1796\u17b6\u1793\u17cb\u1780\u179a\u178e\u17b8 - Construction &amp; Property News\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/construction-property.com\\\/km\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/construction-property.com\\\/km\\\/%e1%9e%94%e1%9e%85%e1%9f%92%e1%9e%85%e1%9e%bb%e1%9e%94%e1%9f%92%e1%9e%94%e1%9e%93%e1%9f%92%e1%9e%93-%e1%9e%80%e1%9f%92%e1%9e%93%e1%9e%bb%e1%9e%84%e1%9e%a7%e1%9e%91%e1%9f%92%e1%9e%99%e1%9e%b6%e1%9e%93\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/construction-property.com\\\/km\\\/%e1%9e%94%e1%9e%85%e1%9f%92%e1%9e%85%e1%9e%bb%e1%9e%94%e1%9f%92%e1%9e%94%e1%9e%93%e1%9f%92%e1%9e%93-%e1%9e%80%e1%9f%92%e1%9e%93%e1%9e%bb%e1%9e%84%e1%9e%a7%e1%9e%91%e1%9f%92%e1%9e%99%e1%9e%b6%e1%9e%93\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/construction-property.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/CPM_8_illegal-Construction_19-08-2022.png\",\"datePublished\":\"2022-08-19T09:08:54+00:00\",\"description\":\"\u1780\u17d2\u179a\u17c4\u1799\u1798\u17b6\u1793\u1780\u17b6\u179a\u1785\u17bb\u17c7\u178f\u17d2\u179a\u17bd\u178f\u1796\u17b7\u1793\u17b7\u178f\u17d2\u1799\u178a\u17c4\u1799\u1795\u17d2\u1791\u17b6\u179b\u17cb\u179a\u1794\u179f\u17cb \u17af\u1780\u17a7\u178f\u17d2\u178f\u1798\u1787\u17b6 \u179f\u17bb\u1795\u17b6\u179a\u17c9\u17b6 \u179a\u178a\u17d2\u178b\u1798\u1793\u17d2\u178f\u17d2\u179a\u17b8\u1780\u17d2\u179a\u179f\u17bd\u1784\u179a\u17c0\u1794\u1785\u17c6\u178a\u17c2\u1793\u178a\u17b8\u1793\u1782\u179a\u17bc\u1794\u1793\u17b8\u1799\u1780\u1798\u17d2\u1798 \u1793\u17b7\u1784\u179f\u17c6\u178e\u1784\u17cb \u1794\u17b6\u1793\u179a\u1780\u1783\u17be\u1789\u1790\u17b6\u179a\u17a0\u17bc\u178f\u178a\u179b\u17cb\u1794\u1785\u17d2\u1785\u17bb\u1794\u17d2\u1794\u1793\u17d2\u1793\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/construction-property.com\\\/km\\\/%e1%9e%94%e1%9e%85%e1%9f%92%e1%9e%85%e1%9e%bb%e1%9e%94%e1%9f%92%e1%9e%94%e1%9e%93%e1%9f%92%e1%9e%93-%e1%9e%80%e1%9f%92%e1%9e%93%e1%9e%bb%e1%9e%84%e1%9e%a7%e1%9e%91%e1%9f%92%e1%9e%99%e1%9e%b6%e1%9e%93\\\/#breadcrumb\"},\"inLanguage\":\"km\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/construction-property.com\\\/km\\\/%e1%9e%94%e1%9e%85%e1%9f%92%e1%9e%85%e1%9e%bb%e1%9e%94%e1%9f%92%e1%9e%94%e1%9e%93%e1%9f%92%e1%9e%93-%e1%9e%80%e1%9f%92%e1%9e%93%e1%9e%bb%e1%9e%84%e1%9e%a7%e1%9e%91%e1%9f%92%e1%9e%99%e1%9e%b6%e1%9e%93\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"km\",\"@id\":\"https:\\\/\\\/construction-property.com\\\/km\\\/%e1%9e%94%e1%9e%85%e1%9f%92%e1%9e%85%e1%9e%bb%e1%9e%94%e1%9f%92%e1%9e%94%e1%9e%93%e1%9f%92%e1%9e%93-%e1%9e%80%e1%9f%92%e1%9e%93%e1%9e%bb%e1%9e%84%e1%9e%a7%e1%9e%91%e1%9f%92%e1%9e%99%e1%9e%b6%e1%9e%93\\\/#primaryimage\",\"url\":\"https:\\\/\\\/construction-property.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/CPM_8_illegal-Construction_19-08-2022.png\",\"contentUrl\":\"https:\\\/\\\/construction-property.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/CPM_8_illegal-Construction_19-08-2022.png\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/construction-property.com\\\/km\\\/%e1%9e%94%e1%9e%85%e1%9f%92%e1%9e%85%e1%9e%bb%e1%9e%94%e1%9f%92%e1%9e%94%e1%9e%93%e1%9f%92%e1%9e%93-%e1%9e%80%e1%9f%92%e1%9e%93%e1%9e%bb%e1%9e%84%e1%9e%a7%e1%9e%91%e1%9f%92%e1%9e%99%e1%9e%b6%e1%9e%93\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/construction-property.com\\\/km\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u1796\u17d0\u178f\u17cc\u1798\u17b6\u1793\u17a2\u1785\u179b\u1793\u1791\u17d2\u179a\u1796\u17d2\u1799\",\"item\":\"https:\\\/\\\/construction-property.com\\\/km\\\/%e1%9e%96%e1%9f%90%e1%9e%8f%e1%9f%8c%e1%9e%98%e1%9e%b6%e1%9e%93%e1%9e%a2%e1%9e%85%e1%9e%9b%e1%9e%93%e1%9e%91%e1%9f%92%e1%9e%9a%e1%9e%96%e1%9f%92%e1%9e%99\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u1796\u17d0\u178f\u17cc\u1798\u17b6\u1793\u1780\u17d2\u1793\u17bb\u1784\u179f\u17d2\u179a\u17bb\u1780\",\"item\":\"https:\\\/\\\/construction-property.com\\\/km\\\/%e1%9e%96%e1%9f%90%e1%9e%8f%e1%9f%8c%e1%9e%98%e1%9e%b6%e1%9e%93%e1%9e%a2%e1%9e%85%e1%9e%9b%e1%9e%93%e1%9e%91%e1%9f%92%e1%9e%9a%e1%9e%96%e1%9f%92%e1%9e%99\\\/%e1%9e%96%e1%9f%90%e1%9e%8f%e1%9f%8c%e1%9e%98%e1%9e%b6%e1%9e%93%e1%9e%80%e1%9f%92%e1%9e%93%e1%9e%bb%e1%9e%84%e1%9e%9f%e1%9f%92%e1%9e%9a%e1%9e%bb%e1%9e%80-%e1%9e%96%e1%9f%90%e1%9e%8f%e1%9f%8c%e1%9e%98\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"\u1794\u1785\u17d2\u1785\u17bb\u1794\u17d2\u1794\u1793\u17d2\u1793 \u1780\u17d2\u1793\u17bb\u1784\u17a7\u1791\u17d2\u1799\u17b6\u1793\u1787\u17b6\u178f\u17b7\u17a2\u1784\u17d2\u1782\u179a\u1798\u17b6\u1793\u179f\u17c6\u178e\u1784\u17cb\u1781\u17bb\u179f\u1785\u17d2\u1794\u17b6\u1794\u17cb\u1787\u17b6\u1784 \u17e8\u1796\u17b6\u1793\u17cb\u1780\u179a\u178e\u17b8\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/construction-property.com\\\/km\\\/#website\",\"url\":\"https:\\\/\\\/construction-property.com\\\/km\\\/\",\"name\":\"Construction &amp; Property News\",\"description\":\"The media that links your business to success\",\"publisher\":{\"@id\":\"https:\\\/\\\/construction-property.com\\\/km\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/construction-property.com\\\/km\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"km\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/construction-property.com\\\/km\\\/#organization\",\"name\":\"Construction & Property News\",\"url\":\"https:\\\/\\\/construction-property.com\\\/km\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"km\",\"@id\":\"https:\\\/\\\/construction-property.com\\\/km\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/construction-property.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/CPM_New-Bridg_19092023.jpg\",\"contentUrl\":\"https:\\\/\\\/construction-property.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/CPM_New-Bridg_19092023.jpg\",\"width\":1200,\"height\":630,\"caption\":\"Construction & Property News\"},\"image\":{\"@id\":\"https:\\\/\\\/construction-property.com\\\/km\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/construction-property.com\\\/km\\\/china-agrees-to-lend-money-to-build-a-new-bridge-connecting-chak-angre-krom-and-prek-pra\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/construction-property.com\\\/km\\\/#\\\/schema\\\/person\\\/2e38ef685b96188d052f0f9dcc8f8772\",\"name\":\"Sommana Yan\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"km\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d1dbef05b6ea51ae966891ce916de51f99304adfcd5ac28edf29472fbb1c9764?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d1dbef05b6ea51ae966891ce916de51f99304adfcd5ac28edf29472fbb1c9764?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d1dbef05b6ea51ae966891ce916de51f99304adfcd5ac28edf29472fbb1c9764?s=96&d=mm&r=g\",\"caption\":\"Sommana Yan\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u1794\u1785\u17d2\u1785\u17bb\u1794\u17d2\u1794\u1793\u17d2\u1793 \u1780\u17d2\u1793\u17bb\u1784\u17a7\u1791\u17d2\u1799\u17b6\u1793\u1787\u17b6\u178f\u17b7\u17a2\u1784\u17d2\u1782\u179a\u1798\u17b6\u1793\u179f\u17c6\u178e\u1784\u17cb\u1781\u17bb\u179f\u1785\u17d2\u1794\u17b6\u1794\u17cb\u1787\u17b6\u1784 \u17e8\u1796\u17b6\u1793\u17cb\u1780\u179a\u178e\u17b8 - Construction &amp; Property News","description":"\u1780\u17d2\u179a\u17c4\u1799\u1798\u17b6\u1793\u1780\u17b6\u179a\u1785\u17bb\u17c7\u178f\u17d2\u179a\u17bd\u178f\u1796\u17b7\u1793\u17b7\u178f\u17d2\u1799\u178a\u17c4\u1799\u1795\u17d2\u1791\u17b6\u179b\u17cb\u179a\u1794\u179f\u17cb \u17af\u1780\u17a7\u178f\u17d2\u178f\u1798\u1787\u17b6 \u179f\u17bb\u1795\u17b6\u179a\u17c9\u17b6 \u179a\u178a\u17d2\u178b\u1798\u1793\u17d2\u178f\u17d2\u179a\u17b8\u1780\u17d2\u179a\u179f\u17bd\u1784\u179a\u17c0\u1794\u1785\u17c6\u178a\u17c2\u1793\u178a\u17b8\u1793\u1782\u179a\u17bc\u1794\u1793\u17b8\u1799\u1780\u1798\u17d2\u1798 \u1793\u17b7\u1784\u179f\u17c6\u178e\u1784\u17cb \u1794\u17b6\u1793\u179a\u1780\u1783\u17be\u1789\u1790\u17b6\u179a\u17a0\u17bc\u178f\u178a\u179b\u17cb\u1794\u1785\u17d2\u1785\u17bb\u1794\u17d2\u1794\u1793\u17d2\u1793","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/construction-property.com\/km\/%e1%9e%94%e1%9e%85%e1%9f%92%e1%9e%85%e1%9e%bb%e1%9e%94%e1%9f%92%e1%9e%94%e1%9e%93%e1%9f%92%e1%9e%93-%e1%9e%80%e1%9f%92%e1%9e%93%e1%9e%bb%e1%9e%84%e1%9e%a7%e1%9e%91%e1%9f%92%e1%9e%99%e1%9e%b6%e1%9e%93\/","og_locale":"en_US","og_type":"article","og_title":"\u1794\u1785\u17d2\u1785\u17bb\u1794\u17d2\u1794\u1793\u17d2\u1793 \u1780\u17d2\u1793\u17bb\u1784\u17a7\u1791\u17d2\u1799\u17b6\u1793\u1787\u17b6\u178f\u17b7\u17a2\u1784\u17d2\u1782\u179a\u1798\u17b6\u1793\u179f\u17c6\u178e\u1784\u17cb\u1781\u17bb\u179f\u1785\u17d2\u1794\u17b6\u1794\u17cb\u1787\u17b6\u1784 \u17e8\u1796\u17b6\u1793\u17cb\u1780\u179a\u178e\u17b8 - Construction &amp; Property News","og_description":"\u1780\u17d2\u179a\u17c4\u1799\u1798\u17b6\u1793\u1780\u17b6\u179a\u1785\u17bb\u17c7\u178f\u17d2\u179a\u17bd\u178f\u1796\u17b7\u1793\u17b7\u178f\u17d2\u1799\u178a\u17c4\u1799\u1795\u17d2\u1791\u17b6\u179b\u17cb\u179a\u1794\u179f\u17cb \u17af\u1780\u17a7\u178f\u17d2\u178f\u1798\u1787\u17b6 \u179f\u17bb\u1795\u17b6\u179a\u17c9\u17b6 \u179a\u178a\u17d2\u178b\u1798\u1793\u17d2\u178f\u17d2\u179a\u17b8\u1780\u17d2\u179a\u179f\u17bd\u1784\u179a\u17c0\u1794\u1785\u17c6\u178a\u17c2\u1793\u178a\u17b8\u1793\u1782\u179a\u17bc\u1794\u1793\u17b8\u1799\u1780\u1798\u17d2\u1798 \u1793\u17b7\u1784\u179f\u17c6\u178e\u1784\u17cb \u1794\u17b6\u1793\u179a\u1780\u1783\u17be\u1789\u1790\u17b6\u179a\u17a0\u17bc\u178f\u178a\u179b\u17cb\u1794\u1785\u17d2\u1785\u17bb\u1794\u17d2\u1794\u1793\u17d2\u1793","og_url":"https:\/\/construction-property.com\/km\/%e1%9e%94%e1%9e%85%e1%9f%92%e1%9e%85%e1%9e%bb%e1%9e%94%e1%9f%92%e1%9e%94%e1%9e%93%e1%9f%92%e1%9e%93-%e1%9e%80%e1%9f%92%e1%9e%93%e1%9e%bb%e1%9e%84%e1%9e%a7%e1%9e%91%e1%9f%92%e1%9e%99%e1%9e%b6%e1%9e%93\/","og_site_name":"Construction &amp; Property News","article_publisher":"https:\/\/construction-property.com\/km\/china-agrees-to-lend-money-to-build-a-new-bridge-connecting-chak-angre-krom-and-prek-pra\/","article_published_time":"2022-08-19T09:08:54+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/construction-property.com\/wp-content\/uploads\/2022\/08\/CPM_8_illegal-Construction_19-08-2022.png","type":"image\/png"}],"author":"Sommana Yan","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Sommana Yan"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/construction-property.com\/km\/%e1%9e%94%e1%9e%85%e1%9f%92%e1%9e%85%e1%9e%bb%e1%9e%94%e1%9f%92%e1%9e%94%e1%9e%93%e1%9f%92%e1%9e%93-%e1%9e%80%e1%9f%92%e1%9e%93%e1%9e%bb%e1%9e%84%e1%9e%a7%e1%9e%91%e1%9f%92%e1%9e%99%e1%9e%b6%e1%9e%93\/#article","isPartOf":{"@id":"https:\/\/construction-property.com\/km\/%e1%9e%94%e1%9e%85%e1%9f%92%e1%9e%85%e1%9e%bb%e1%9e%94%e1%9f%92%e1%9e%94%e1%9e%93%e1%9f%92%e1%9e%93-%e1%9e%80%e1%9f%92%e1%9e%93%e1%9e%bb%e1%9e%84%e1%9e%a7%e1%9e%91%e1%9f%92%e1%9e%99%e1%9e%b6%e1%9e%93\/"},"author":{"name":"Sommana Yan","@id":"https:\/\/construction-property.com\/km\/#\/schema\/person\/2e38ef685b96188d052f0f9dcc8f8772"},"headline":"\u1794\u1785\u17d2\u1785\u17bb\u1794\u17d2\u1794\u1793\u17d2\u1793 \u1780\u17d2\u1793\u17bb\u1784\u17a7\u1791\u17d2\u1799\u17b6\u1793\u1787\u17b6\u178f\u17b7\u17a2\u1784\u17d2\u1782\u179a\u1798\u17b6\u1793\u179f\u17c6\u178e\u1784\u17cb\u1781\u17bb\u179f\u1785\u17d2\u1794\u17b6\u1794\u17cb\u1787\u17b6\u1784 \u17e8\u1796\u17b6\u1793\u17cb\u1780\u179a\u178e\u17b8","datePublished":"2022-08-19T09:08:54+00:00","mainEntityOfPage":{"@id":"https:\/\/construction-property.com\/km\/%e1%9e%94%e1%9e%85%e1%9f%92%e1%9e%85%e1%9e%bb%e1%9e%94%e1%9f%92%e1%9e%94%e1%9e%93%e1%9f%92%e1%9e%93-%e1%9e%80%e1%9f%92%e1%9e%93%e1%9e%bb%e1%9e%84%e1%9e%a7%e1%9e%91%e1%9f%92%e1%9e%99%e1%9e%b6%e1%9e%93\/"},"wordCount":0,"commentCount":0,"publisher":{"@id":"https:\/\/construction-property.com\/km\/#organization"},"image":{"@id":"https:\/\/construction-property.com\/km\/%e1%9e%94%e1%9e%85%e1%9f%92%e1%9e%85%e1%9e%bb%e1%9e%94%e1%9f%92%e1%9e%94%e1%9e%93%e1%9f%92%e1%9e%93-%e1%9e%80%e1%9f%92%e1%9e%93%e1%9e%bb%e1%9e%84%e1%9e%a7%e1%9e%91%e1%9f%92%e1%9e%99%e1%9e%b6%e1%9e%93\/#primaryimage"},"thumbnailUrl":"https:\/\/construction-property.com\/wp-content\/uploads\/2022\/08\/CPM_8_illegal-Construction_19-08-2022.png","keywords":["\u1785\u17d2\u1794\u17b6\u1794\u17cb \u1793\u17b7\u1784\u1794\u1789\u17d2\u1789\u17b6\u178f\u17d2\u178f\u17b7","\u1785\u17d2\u1794\u17b6\u1794\u17cb \u1793\u17b7\u1784\u1794\u1789\u17d2\u1789\u17b6\u178f\u17d2\u178f\u17b7"],"articleSection":["\u1796\u17d0\u178f\u17cc\u1798\u17b6\u1793\u17a2\u1785\u179b\u1793\u1791\u17d2\u179a\u1796\u17d2\u1799","\u1796\u17d0\u178f\u17cc\u1798\u17b6\u1793\u1780\u17d2\u1793\u17bb\u1784\u179f\u17d2\u179a\u17bb\u1780","Uncategorized"],"inLanguage":"km","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/construction-property.com\/km\/%e1%9e%94%e1%9e%85%e1%9f%92%e1%9e%85%e1%9e%bb%e1%9e%94%e1%9f%92%e1%9e%94%e1%9e%93%e1%9f%92%e1%9e%93-%e1%9e%80%e1%9f%92%e1%9e%93%e1%9e%bb%e1%9e%84%e1%9e%a7%e1%9e%91%e1%9f%92%e1%9e%99%e1%9e%b6%e1%9e%93\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/construction-property.com\/km\/%e1%9e%94%e1%9e%85%e1%9f%92%e1%9e%85%e1%9e%bb%e1%9e%94%e1%9f%92%e1%9e%94%e1%9e%93%e1%9f%92%e1%9e%93-%e1%9e%80%e1%9f%92%e1%9e%93%e1%9e%bb%e1%9e%84%e1%9e%a7%e1%9e%91%e1%9f%92%e1%9e%99%e1%9e%b6%e1%9e%93\/","url":"https:\/\/construction-property.com\/km\/%e1%9e%94%e1%9e%85%e1%9f%92%e1%9e%85%e1%9e%bb%e1%9e%94%e1%9f%92%e1%9e%94%e1%9e%93%e1%9f%92%e1%9e%93-%e1%9e%80%e1%9f%92%e1%9e%93%e1%9e%bb%e1%9e%84%e1%9e%a7%e1%9e%91%e1%9f%92%e1%9e%99%e1%9e%b6%e1%9e%93\/","name":"\u1794\u1785\u17d2\u1785\u17bb\u1794\u17d2\u1794\u1793\u17d2\u1793 \u1780\u17d2\u1793\u17bb\u1784\u17a7\u1791\u17d2\u1799\u17b6\u1793\u1787\u17b6\u178f\u17b7\u17a2\u1784\u17d2\u1782\u179a\u1798\u17b6\u1793\u179f\u17c6\u178e\u1784\u17cb\u1781\u17bb\u179f\u1785\u17d2\u1794\u17b6\u1794\u17cb\u1787\u17b6\u1784 \u17e8\u1796\u17b6\u1793\u17cb\u1780\u179a\u178e\u17b8 - Construction &amp; Property News","isPartOf":{"@id":"https:\/\/construction-property.com\/km\/#website"},"primaryImageOfPage":{"@id":"https:\/\/construction-property.com\/km\/%e1%9e%94%e1%9e%85%e1%9f%92%e1%9e%85%e1%9e%bb%e1%9e%94%e1%9f%92%e1%9e%94%e1%9e%93%e1%9f%92%e1%9e%93-%e1%9e%80%e1%9f%92%e1%9e%93%e1%9e%bb%e1%9e%84%e1%9e%a7%e1%9e%91%e1%9f%92%e1%9e%99%e1%9e%b6%e1%9e%93\/#primaryimage"},"image":{"@id":"https:\/\/construction-property.com\/km\/%e1%9e%94%e1%9e%85%e1%9f%92%e1%9e%85%e1%9e%bb%e1%9e%94%e1%9f%92%e1%9e%94%e1%9e%93%e1%9f%92%e1%9e%93-%e1%9e%80%e1%9f%92%e1%9e%93%e1%9e%bb%e1%9e%84%e1%9e%a7%e1%9e%91%e1%9f%92%e1%9e%99%e1%9e%b6%e1%9e%93\/#primaryimage"},"thumbnailUrl":"https:\/\/construction-property.com\/wp-content\/uploads\/2022\/08\/CPM_8_illegal-Construction_19-08-2022.png","datePublished":"2022-08-19T09:08:54+00:00","description":"\u1780\u17d2\u179a\u17c4\u1799\u1798\u17b6\u1793\u1780\u17b6\u179a\u1785\u17bb\u17c7\u178f\u17d2\u179a\u17bd\u178f\u1796\u17b7\u1793\u17b7\u178f\u17d2\u1799\u178a\u17c4\u1799\u1795\u17d2\u1791\u17b6\u179b\u17cb\u179a\u1794\u179f\u17cb \u17af\u1780\u17a7\u178f\u17d2\u178f\u1798\u1787\u17b6 \u179f\u17bb\u1795\u17b6\u179a\u17c9\u17b6 \u179a\u178a\u17d2\u178b\u1798\u1793\u17d2\u178f\u17d2\u179a\u17b8\u1780\u17d2\u179a\u179f\u17bd\u1784\u179a\u17c0\u1794\u1785\u17c6\u178a\u17c2\u1793\u178a\u17b8\u1793\u1782\u179a\u17bc\u1794\u1793\u17b8\u1799\u1780\u1798\u17d2\u1798 \u1793\u17b7\u1784\u179f\u17c6\u178e\u1784\u17cb \u1794\u17b6\u1793\u179a\u1780\u1783\u17be\u1789\u1790\u17b6\u179a\u17a0\u17bc\u178f\u178a\u179b\u17cb\u1794\u1785\u17d2\u1785\u17bb\u1794\u17d2\u1794\u1793\u17d2\u1793","breadcrumb":{"@id":"https:\/\/construction-property.com\/km\/%e1%9e%94%e1%9e%85%e1%9f%92%e1%9e%85%e1%9e%bb%e1%9e%94%e1%9f%92%e1%9e%94%e1%9e%93%e1%9f%92%e1%9e%93-%e1%9e%80%e1%9f%92%e1%9e%93%e1%9e%bb%e1%9e%84%e1%9e%a7%e1%9e%91%e1%9f%92%e1%9e%99%e1%9e%b6%e1%9e%93\/#breadcrumb"},"inLanguage":"km","potentialAction":[{"@type":"ReadAction","target":["https:\/\/construction-property.com\/km\/%e1%9e%94%e1%9e%85%e1%9f%92%e1%9e%85%e1%9e%bb%e1%9e%94%e1%9f%92%e1%9e%94%e1%9e%93%e1%9f%92%e1%9e%93-%e1%9e%80%e1%9f%92%e1%9e%93%e1%9e%bb%e1%9e%84%e1%9e%a7%e1%9e%91%e1%9f%92%e1%9e%99%e1%9e%b6%e1%9e%93\/"]}]},{"@type":"ImageObject","inLanguage":"km","@id":"https:\/\/construction-property.com\/km\/%e1%9e%94%e1%9e%85%e1%9f%92%e1%9e%85%e1%9e%bb%e1%9e%94%e1%9f%92%e1%9e%94%e1%9e%93%e1%9f%92%e1%9e%93-%e1%9e%80%e1%9f%92%e1%9e%93%e1%9e%bb%e1%9e%84%e1%9e%a7%e1%9e%91%e1%9f%92%e1%9e%99%e1%9e%b6%e1%9e%93\/#primaryimage","url":"https:\/\/construction-property.com\/wp-content\/uploads\/2022\/08\/CPM_8_illegal-Construction_19-08-2022.png","contentUrl":"https:\/\/construction-property.com\/wp-content\/uploads\/2022\/08\/CPM_8_illegal-Construction_19-08-2022.png","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/construction-property.com\/km\/%e1%9e%94%e1%9e%85%e1%9f%92%e1%9e%85%e1%9e%bb%e1%9e%94%e1%9f%92%e1%9e%94%e1%9e%93%e1%9f%92%e1%9e%93-%e1%9e%80%e1%9f%92%e1%9e%93%e1%9e%bb%e1%9e%84%e1%9e%a7%e1%9e%91%e1%9f%92%e1%9e%99%e1%9e%b6%e1%9e%93\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/construction-property.com\/km\/"},{"@type":"ListItem","position":2,"name":"\u1796\u17d0\u178f\u17cc\u1798\u17b6\u1793\u17a2\u1785\u179b\u1793\u1791\u17d2\u179a\u1796\u17d2\u1799","item":"https:\/\/construction-property.com\/km\/%e1%9e%96%e1%9f%90%e1%9e%8f%e1%9f%8c%e1%9e%98%e1%9e%b6%e1%9e%93%e1%9e%a2%e1%9e%85%e1%9e%9b%e1%9e%93%e1%9e%91%e1%9f%92%e1%9e%9a%e1%9e%96%e1%9f%92%e1%9e%99\/"},{"@type":"ListItem","position":3,"name":"\u1796\u17d0\u178f\u17cc\u1798\u17b6\u1793\u1780\u17d2\u1793\u17bb\u1784\u179f\u17d2\u179a\u17bb\u1780","item":"https:\/\/construction-property.com\/km\/%e1%9e%96%e1%9f%90%e1%9e%8f%e1%9f%8c%e1%9e%98%e1%9e%b6%e1%9e%93%e1%9e%a2%e1%9e%85%e1%9e%9b%e1%9e%93%e1%9e%91%e1%9f%92%e1%9e%9a%e1%9e%96%e1%9f%92%e1%9e%99\/%e1%9e%96%e1%9f%90%e1%9e%8f%e1%9f%8c%e1%9e%98%e1%9e%b6%e1%9e%93%e1%9e%80%e1%9f%92%e1%9e%93%e1%9e%bb%e1%9e%84%e1%9e%9f%e1%9f%92%e1%9e%9a%e1%9e%bb%e1%9e%80-%e1%9e%96%e1%9f%90%e1%9e%8f%e1%9f%8c%e1%9e%98\/"},{"@type":"ListItem","position":4,"name":"\u1794\u1785\u17d2\u1785\u17bb\u1794\u17d2\u1794\u1793\u17d2\u1793 \u1780\u17d2\u1793\u17bb\u1784\u17a7\u1791\u17d2\u1799\u17b6\u1793\u1787\u17b6\u178f\u17b7\u17a2\u1784\u17d2\u1782\u179a\u1798\u17b6\u1793\u179f\u17c6\u178e\u1784\u17cb\u1781\u17bb\u179f\u1785\u17d2\u1794\u17b6\u1794\u17cb\u1787\u17b6\u1784 \u17e8\u1796\u17b6\u1793\u17cb\u1780\u179a\u178e\u17b8"}]},{"@type":"WebSite","@id":"https:\/\/construction-property.com\/km\/#website","url":"https:\/\/construction-property.com\/km\/","name":"Construction &amp; Property News","description":"The media that links your business to success","publisher":{"@id":"https:\/\/construction-property.com\/km\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/construction-property.com\/km\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"km"},{"@type":"Organization","@id":"https:\/\/construction-property.com\/km\/#organization","name":"Construction & Property News","url":"https:\/\/construction-property.com\/km\/","logo":{"@type":"ImageObject","inLanguage":"km","@id":"https:\/\/construction-property.com\/km\/#\/schema\/logo\/image\/","url":"https:\/\/construction-property.com\/wp-content\/uploads\/2023\/09\/CPM_New-Bridg_19092023.jpg","contentUrl":"https:\/\/construction-property.com\/wp-content\/uploads\/2023\/09\/CPM_New-Bridg_19092023.jpg","width":1200,"height":630,"caption":"Construction & Property News"},"image":{"@id":"https:\/\/construction-property.com\/km\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/construction-property.com\/km\/china-agrees-to-lend-money-to-build-a-new-bridge-connecting-chak-angre-krom-and-prek-pra\/"]},{"@type":"Person","@id":"https:\/\/construction-property.com\/km\/#\/schema\/person\/2e38ef685b96188d052f0f9dcc8f8772","name":"Sommana Yan","image":{"@type":"ImageObject","inLanguage":"km","@id":"https:\/\/secure.gravatar.com\/avatar\/d1dbef05b6ea51ae966891ce916de51f99304adfcd5ac28edf29472fbb1c9764?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d1dbef05b6ea51ae966891ce916de51f99304adfcd5ac28edf29472fbb1c9764?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d1dbef05b6ea51ae966891ce916de51f99304adfcd5ac28edf29472fbb1c9764?s=96&d=mm&r=g","caption":"Sommana Yan"}}]}},"_links":{"self":[{"href":"https:\/\/construction-property.com\/km\/wp-json\/wp\/v2\/posts\/78124","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/construction-property.com\/km\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/construction-property.com\/km\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/construction-property.com\/km\/wp-json\/wp\/v2\/users\/84"}],"replies":[{"embeddable":true,"href":"https:\/\/construction-property.com\/km\/wp-json\/wp\/v2\/comments?post=78124"}],"version-history":[{"count":0,"href":"https:\/\/construction-property.com\/km\/wp-json\/wp\/v2\/posts\/78124\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/construction-property.com\/km\/wp-json\/wp\/v2\/media\/78125"}],"wp:attachment":[{"href":"https:\/\/construction-property.com\/km\/wp-json\/wp\/v2\/media?parent=78124"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/construction-property.com\/km\/wp-json\/wp\/v2\/categories?post=78124"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/construction-property.com\/km\/wp-json\/wp\/v2\/tags?post=78124"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}